{"id":2660,"date":"2020-07-06T08:47:38","date_gmt":"2020-07-06T06:47:38","guid":{"rendered":"http:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1.png"},"modified":"2020-07-06T08:47:38","modified_gmt":"2020-07-06T06:47:38","slug":"chema-campos-sobre-mi-1-2","status":"inherit","type":"attachment","link":"https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main","title":{"rendered":"chema-campos-sobre-mi-1"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2660","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>chema-campos-sobre-mi-1 - CHEMA CAMPOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"chema-campos-sobre-mi-1 - CHEMA CAMPOS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main\" \/>\n<meta property=\"og:site_name\" content=\"CHEMA CAMPOS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/chema.campossoler\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"501\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/about-me\\\/chema-campos-sobre-mi-1-2\\\/#main\",\"url\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/about-me\\\/chema-campos-sobre-mi-1-2\\\/#main\",\"name\":\"chema-campos-sobre-mi-1 - CHEMA CAMPOS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/#website\"},\"datePublished\":\"2020-07-06T06:47:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/about-me\\\/chema-campos-sobre-mi-1-2\\\/#main#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/chemacampos.es\\\/en\\\/about-me\\\/chema-campos-sobre-mi-1-2\\\/#main\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/about-me\\\/chema-campos-sobre-mi-1-2\\\/#main#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About me\",\"item\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/about-me\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"chema-campos-sobre-mi-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/\",\"name\":\"CHEMA CAMPOS\",\"description\":\"Customized energy solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/chemacampos.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"chema-campos-sobre-mi-1 - CHEMA CAMPOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main\/","og_locale":"en_US","og_type":"article","og_title":"chema-campos-sobre-mi-1 - CHEMA CAMPOS","og_url":"https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main","og_site_name":"CHEMA CAMPOS","article_publisher":"https:\/\/www.facebook.com\/chema.campossoler","og_image":[{"width":501,"height":600,"url":"https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main","url":"https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main","name":"chema-campos-sobre-mi-1 - CHEMA CAMPOS","isPartOf":{"@id":"https:\/\/chemacampos.es\/en\/#website"},"datePublished":"2020-07-06T06:47:38+00:00","breadcrumb":{"@id":"https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/chemacampos.es\/en\/about-me\/chema-campos-sobre-mi-1-2\/#main#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/chemacampos.es\/en\/home\/"},{"@type":"ListItem","position":2,"name":"About me","item":"https:\/\/chemacampos.es\/en\/about-me\/"},{"@type":"ListItem","position":3,"name":"chema-campos-sobre-mi-1"}]},{"@type":"WebSite","@id":"https:\/\/chemacampos.es\/en\/#website","url":"https:\/\/chemacampos.es\/en\/","name":"CHEMA CAMPOS","description":"Customized energy solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chemacampos.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1.png'><img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"300\" src=\"https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1-251x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1-251x300.png 251w, https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1.png 501w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":501,"height":600,"file":"2020\/07\/chema-campos-sobre-mi-1-1.png","sizes":{"medium":{"file":"chema-campos-sobre-mi-1-1-251x300.png","width":251,"height":300,"mime_type":"image\/png","source_url":"https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1-251x300.png"},"thumbnail":{"file":"chema-campos-sobre-mi-1-1-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1-150x150.png"},"full":{"file":"chema-campos-sobre-mi-1-1.png","width":501,"height":600,"mime_type":"image\/png","source_url":"https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2649,"source_url":"https:\/\/chemacampos.es\/wp-content\/uploads\/2020\/07\/chema-campos-sobre-mi-1-1.png","_links":{"self":[{"href":"https:\/\/chemacampos.es\/en\/wp-json\/wp\/v2\/media\/2660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chemacampos.es\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/chemacampos.es\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/chemacampos.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chemacampos.es\/en\/wp-json\/wp\/v2\/comments?post=2660"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":2649,"href":"https:\/\/chemacampos.es\/en\/wp-json\/wp\/v2\/pages\/2649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}